{"id":4529,"date":"2024-10-15T13:25:58","date_gmt":"2024-10-15T12:25:58","guid":{"rendered":"https:\/\/silenthome.com\/produto\/mesa-de-apoio-atomos-em-dourado\/"},"modified":"2026-04-01T23:33:43","modified_gmt":"2026-04-01T22:33:43","slug":"mesa-auxiliar-atomos-en-dorado","status":"publish","type":"product","link":"https:\/\/silenthome.com\/es\/produto\/mesa-de-apoio-atomos-em-dourado\/","title":{"rendered":"MESA DE CENTRO ATOMS EN ORO"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>La mesa auxiliar \u00c1tomos presenta una estructura en forma de cono con una base chapada en oro, combinada con una tapa circular de cristal oscuro. Ideal como mesa auxiliar en salones, dormitorios o zonas de estar, ofrece un lugar elegante para colocar objetos decorativos o sostener bebidas. Su acabado dorado a\u00f1ade <strong>elegancia y sofisticaci\u00f3n<\/strong>convirti\u00e9ndolo en un <strong>centro de mesa<\/strong> en la decoraci\u00f3n de su espacio<\/p>","protected":false},"featured_media":7020,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[62,61,164],"product_tag":[],"class_list":{"0":"post-4529","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-mesas-de-centro-e-apoio","7":"product_cat-mobiliario","8":"product_cat-promocoes","10":"first","11":"outofstock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/silenthome.com\/es\/wp-json\/wp\/v2\/product\/4529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/silenthome.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/silenthome.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/silenthome.com\/es\/wp-json\/wp\/v2\/comments?post=4529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/silenthome.com\/es\/wp-json\/wp\/v2\/media\/7020"}],"wp:attachment":[{"href":"https:\/\/silenthome.com\/es\/wp-json\/wp\/v2\/media?parent=4529"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/silenthome.com\/es\/wp-json\/wp\/v2\/product_brand?post=4529"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/silenthome.com\/es\/wp-json\/wp\/v2\/product_cat?post=4529"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/silenthome.com\/es\/wp-json\/wp\/v2\/product_tag?post=4529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}